{"id":3911,"date":"2022-09-11T18:40:02","date_gmt":"2022-09-11T18:40:02","guid":{"rendered":"http:\/\/sgl.cl\/sgl\/?p=3911"},"modified":"2022-09-11T18:40:07","modified_gmt":"2022-09-11T18:40:07","slug":"la-importancia-de-ser-paciente-mientras-te-sanas","status":"publish","type":"post","link":"https:\/\/sgl.cl\/sgl\/2022\/09\/11\/la-importancia-de-ser-paciente-mientras-te-sanas\/","title":{"rendered":"La importancia de ser paciente mientras te sanas"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La paciencia parece ser algo que tenemos o no tenemos, como un rasgo de personalidad. Sin embargo, eso no es cierto:&nbsp;<strong>la paciencia se puede aprender y, especialmente a medida que envejecemos, se vuelve m\u00e1s esencial.&nbsp;<\/strong><\/p><\/blockquote>\n\n\n\n<p>Despu\u00e9s de una lesi\u00f3n o enfermedad, nuestra voluntad para ser pacientes al manejar la recuperaci\u00f3n es capaz de determinar si la curaci\u00f3n tendr\u00e1 los efectos positivos que esperamos\u2026 o no.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>C\u00d3MO DESARROLLAR LA PACIENCIA<\/strong><\/h2>\n\n\n\n<p><strong>\u00bfQu\u00e9 es la paciencia y por qu\u00e9 es tan dif\u00edcil para algunas personas desarrollarla<\/strong>? \u00bfC\u00f3mo se puede aprender a ser paciente mientras se cura de una lesi\u00f3n o enfermedad?&nbsp;<\/p>\n\n\n\n<p>La palabra misma comparte su origen con la palabra \u201cpaciente\u201d, como en alguien que est\u00e1 bajo el cuidado de un profesional m\u00e9dico.&nbsp;<strong>Ambas palabras se derivan de una palabra latina que significa&nbsp;<\/strong><strong><em>sufrir<\/em><\/strong><strong>. A menudo es sin\u00f3nimo de un retraso en la gratificaci\u00f3n, el autocontrol y la disciplina.<\/strong><\/p>\n\n\n\n<p>Es dif\u00edcil porque la gratificaci\u00f3n instant\u00e1nea es f\u00e1cil de convertir en un h\u00e1bito.&nbsp;<strong>Pero la paciencia no tiene que sentirse como sufrimiento.<\/strong>&nbsp;En cambio, puedes desarrollar la paciencia de una manera que puedes disfrutar, a trav\u00e9s del&nbsp;<strong>pensamiento futuro epis\u00f3dico<\/strong>: imag\u00ednate a ti mismo en 5 eventos futuros positivos \u2013un d\u00eda, una semana, un mes, 3 meses y un a\u00f1o.<\/p>\n\n\n\n<p>En una semana, imag\u00ednate conociendo a tu fisioterapeuta y mostrando una mejora medida. En un mes, imag\u00ednate caminando en la caminadora durante 30 minutos y sinti\u00e9ndote tremendo, o estirando los brazos por encima de la cabeza sin molestias. Luego, en 3 meses, imagina jugar al tenis sin dolor. Finalmente, imag\u00ednate recuperado dentro de un a\u00f1o y participando en una actividad que no podr\u00edas haber so\u00f1ado antes, \u00a1como correr una media marat\u00f3n!<\/p>\n\n\n\n<p>Se ha demostrado que el pensamiento futuro epis\u00f3dico reduce lo que se conoce como descuento por demora, que es la idea de que es mejor satisfacer los deseos inmediatos en lugar de tratar de anticiparse a algo mejor m\u00e1s adelante. En cambio,&nbsp;<strong>el pensamiento futuro epis\u00f3dico proporciona pistas que le dan una idea ahora de ese futuro algo mejor<\/strong>.&nbsp;<strong>Hacer esto a diario mejorar\u00e1 tu capacidad para ejercitar la paciencia y cosechar sus recompensas.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PACIENCIA PARA SANAR \u2013 O LO EMPEORAR\u00c1S.&nbsp;<\/strong><\/h2>\n\n\n\n<p>\u201c\u2019Es posible que te sientas mejor\u2019, me dijo mi cirujano 3 semanas despu\u00e9s de mi cirug\u00eda de hernia, \u2018pero eso no significa que est\u00e9s mejor\u2019\u00bb, relata el escritor Stephen L. Antczak.&nbsp;<\/p>\n\n\n\n<p>Le hab\u00eda estado explicando que se hab\u00eda sentido lo suficientemente bien durante la \u00faltima semana para hacer algunas flexiones con facilidad, unas 10 a la vez. El especialista le pidi\u00f3 que dejara de hacer esto inmediatamente. Reci\u00e9n ser\u00eda capaz de hacer flexiones, sentadillas y volver a correr despu\u00e9s de la sexta semana. Hasta entonces, no deb\u00eda hacer nada m\u00e1s extenuante que caminar casualmente y no levantar nada m\u00e1s pesado que un bid\u00f3n de leche.&nbsp;<strong>Su<\/strong>&nbsp;<strong>consejo era ser paciente y dejar que el proceso de curaci\u00f3n hiciera su trabajo.<\/strong><\/p>\n\n\n\n<p>\u201c\u00a1Afortunadamente, el Dr. Saunders intervino antes de que hiciera algo est\u00fapido y lo empeorara!\u201d, reflexiona Antczak. \u201cSin embargo, sucede que un paciente decide jugar al baloncesto una semana despu\u00e9s de la cirug\u00eda y abre la incisi\u00f3n.&nbsp;<strong>Lo \u00fanico que se puede hacer entonces es dejar que la herida cicatrice\u201d.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PACIENCIA PARA NO RENDIRTE ANTES DE TIEMPO.<\/strong><\/h2>\n\n\n\n<p>La fisioterapia tambi\u00e9n requiere paciencia. Las sesiones individuales de terapia f\u00edsica pueden sentirse como si en realidad no estuvieras haciendo nada o incluso pueden resultar inc\u00f3modas, especialmente si se realizan en tu propio hogar. Pero, nuevamente,&nbsp;<strong>esto requiere tener paciencia tanto con el proceso como contigo mismo.<\/strong><\/p>\n\n\n\n<p>Cassandra Hogan es una fisioterapeuta en Florida, Estados Unidos, que se especializa en ayudar a pacientes neurol\u00f3gicos, como aquellos que han sufrido&nbsp;<a href=\"https:\/\/www.nextavenue.org\/could-it-be-a-stroke\/\">un derrame cerebral<\/a>&nbsp;o una lesi\u00f3n en la m\u00e9dula espinal. A diferencia de la recuperaci\u00f3n de una cirug\u00eda de hernia, dice que \u00abm\u00e1s es mejor\u00bb con respecto a la fisioterapia en estos casos \u2013 se trata de hacer todo lo posible y lo antes posible.<\/p>\n\n\n\n<p>\u00abReevaluamos cada 4 a 8 semanas, dependiendo de la condici\u00f3n\u00bb, dijo Hogan. \u00abNormalmente, hacemos medidas de resultados como fuerza, mejor rango de movimiento o una prueba de caminar para ver qu\u00e9 tan r\u00e1pido o seguro se puede caminar\u00bb.<\/p>\n\n\n\n<p><strong>Esto podr\u00eda significar no ser capaz de esforzarse tanto como uno quisiera, pero a\u00fan as\u00ed intentarlo, y requiere paciencia con uno mismo para comprender que el progreso requiere tiempo y esfuerzo<\/strong>. De manera similar, los pacientes mayores tienden a no completar sus ejercicios de fisioterapia en el hogar, lo que se hace evidente cuando visitan a su fisioterapeuta para medir el progreso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PACIENCIA PARA INTENTARLO INCLUSO AUNQUE NO QUIERAS.&nbsp;<\/strong><\/h2>\n\n\n\n<p>Tony Horton, el creador del popular entrenamiento&nbsp;<em>P90X<\/em>&nbsp;y&nbsp;<a href=\"https:\/\/powernationfitness.org\/\"><em>The Power of Four<\/em><\/a>, comprende las pruebas de una larga recuperaci\u00f3n de una enfermedad devastadora. Un ataque de culebrilla en su o\u00eddo lo llev\u00f3 al s\u00edndrome de Ramsey Hunt (que actualmente afecta al cantante Justin Bieber) y la par\u00e1lisis de Bell. De repente,&nbsp;<strong>un tipo que pod\u00eda hacer cuarenta dominadas de una sola vez ni siquiera pod\u00eda pararse sobre sus propios pies.<\/strong><\/p>\n\n\n\n<p>\u00abNo pod\u00eda levantarme de la cama\u00bb, dijo Horton. \u00abNo pod\u00eda comer, no pod\u00eda beber. Perd\u00ed 25 kilos. Estaba vomitando todo el tiempo\u00bb. Simplemente girar la cabeza de un lado a otro lo enfermaba. \u00abNo pude hacer nada f\u00edsicamente durante 2 meses\u00bb. Eventualmente, pudo caminar en una caminadora durante diez minutos. \u00abPero luego tuve que sentarme durante dos horas. Y, a veces, me hac\u00eda vomitar\u00bb.<\/p>\n\n\n\n<p><strong>Su fisioterapeuta le dijo que su recuperaci\u00f3n depend\u00eda de lo duro que quisiera trabajar<\/strong>. \u00abSegu\u00ed intent\u00e1ndolo y segu\u00ed empujando\u00bb, dijo Horton. \u00abPero lo que sucede es que debido a que&nbsp;<strong>es tan debilitante, tan abrumador y tan doloroso, muchas personas simplemente se cierran. No quieren pasar por eso\u00bb.<\/strong><\/p>\n\n\n\n<p>En esos momentos hay que aprender a tener paciencia con uno mismo,<strong>\u00a0darse cuenta de que el progreso puede no ser perceptible momento a momento y no desanimarse<\/strong>. Si solo puedes hacer 10 minutos en la caminadora hoy, tal vez pueda hacer 11 -o 5- ma\u00f1ana. Lo realmente importante es que no te rindas.<\/p>\n\n\n\n<p>Fuente: Espacio Mutuo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La paciencia parece ser algo que tenemos o no tenemos, como un rasgo de personalidad. Sin embargo, eso no es&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-3911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espacio-mutuo"],"_links":{"self":[{"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/posts\/3911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/comments?post=3911"}],"version-history":[{"count":1,"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/posts\/3911\/revisions"}],"predecessor-version":[{"id":3913,"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/posts\/3911\/revisions\/3913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/media\/3912"}],"wp:attachment":[{"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/media?parent=3911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/categories?post=3911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgl.cl\/sgl\/wp-json\/wp\/v2\/tags?post=3911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}